{"id":9449,"count":1,"description":"","link":"https:\/\/themediabeast.com\/resources\/category\/metal-roofing\/","name":"Metal Roofing","slug":"metal-roofing","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v17.8 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Metal Roofing Archives - MMG Resources<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/themediabeast.com\/resources\/category\/metal-roofing\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Metal Roofing Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/themediabeast.com\/resources\/category\/metal-roofing\/\" \/>\n<meta property=\"og:site_name\" content=\"MMG Resources\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/themediabeast.com\\\/resources\\\/category\\\/metal-roofing\\\/\",\"url\":\"https:\\\/\\\/themediabeast.com\\\/resources\\\/category\\\/metal-roofing\\\/\",\"name\":\"Metal Roofing Archives - MMG Resources\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/themediabeast.com\\\/resources\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/themediabeast.com\\\/resources\\\/category\\\/metal-roofing\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/themediabeast.com\\\/resources\\\/category\\\/metal-roofing\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/themediabeast.com\\\/resources\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Metal Roofing\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/themediabeast.com\\\/resources\\\/#website\",\"url\":\"https:\\\/\\\/themediabeast.com\\\/resources\\\/\",\"name\":\"MMG Resources\",\"description\":\"Company Portal\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/themediabeast.com\\\/resources\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Metal Roofing Archives - MMG Resources","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/themediabeast.com\/resources\/category\/metal-roofing\/","og_locale":"en_US","og_type":"article","og_title":"Metal Roofing Archives","og_url":"https:\/\/themediabeast.com\/resources\/category\/metal-roofing\/","og_site_name":"MMG Resources","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/themediabeast.com\/resources\/category\/metal-roofing\/","url":"https:\/\/themediabeast.com\/resources\/category\/metal-roofing\/","name":"Metal Roofing Archives - MMG Resources","isPartOf":{"@id":"https:\/\/themediabeast.com\/resources\/#website"},"breadcrumb":{"@id":"https:\/\/themediabeast.com\/resources\/category\/metal-roofing\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/themediabeast.com\/resources\/category\/metal-roofing\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/themediabeast.com\/resources\/"},{"@type":"ListItem","position":2,"name":"Metal Roofing"}]},{"@type":"WebSite","@id":"https:\/\/themediabeast.com\/resources\/#website","url":"https:\/\/themediabeast.com\/resources\/","name":"MMG Resources","description":"Company Portal","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/themediabeast.com\/resources\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/themediabeast.com\/resources\/wp-json\/wp\/v2\/categories\/9449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/themediabeast.com\/resources\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/themediabeast.com\/resources\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/themediabeast.com\/resources\/wp-json\/wp\/v2\/posts?categories=9449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}